{"id":30119,"date":"2024-10-07T01:53:35","date_gmt":"2024-10-07T01:53:35","guid":{"rendered":"https:\/\/www.harsle.com\/?p=30119"},"modified":"2024-10-16T02:24:14","modified_gmt":"2024-10-16T02:24:14","slug":"brazilian-customers-factory-exploration","status":"publish","type":"post","link":"https:\/\/www.harsle.com\/de\/brazilian-customers-factory-exploration\/","title":{"rendered":"Fabrikerkundung eines brasilianischen Kunden"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Wir haben uns sehr gefreut, unseren gesch\u00e4tzten brasilianischen Kunden herzlich willkommen hei\u00dfen zu k\u00f6nnen. Er hat unser Werk mit seiner Anwesenheit beehrt und damit den Beginn einer Reise voller Versprechen und Zusammenarbeit markiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Von Anfang an war klar, dass dieser Besuch mehr als nur eine Routineinspektion war \u2013 er bot die Gelegenheit, Beziehungen zu st\u00e4rken und dauerhafte Verbindungen zu kn\u00fcpfen. Unsere brasilianischen G\u00e4ste erhielten eine ausf\u00fchrliche F\u00fchrung durch unsere Anlagen und konnten sich so aus erster Hand von dem Engagement und der Expertise \u00fcberzeugen, die jedem Aspekt unserer Gesch\u00e4ftst\u00e4tigkeit zugrunde liegen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als sie sich verabschiedeten und nach Hause zur\u00fcckkehrten, waren wir zutiefst dankbar, einen so gesch\u00e4tzten Partner bei uns begr\u00fc\u00dfen zu d\u00fcrfen. Ihre Zufriedenheit ist ein Beweis f\u00fcr unser unerm\u00fcdliches Engagement f\u00fcr Spitzenleistungen, und wir freuen uns auf die vielen Erfolge, die uns in unserer weiteren Partnerschaft bevorstehen.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1000\" height=\"749\" data-id=\"40153\" src=\"https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-297.png\" alt=\"Fabrikerkundung eines brasilianischen Kunden\" class=\"wp-image-40153\" srcset=\"https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-297.png 1000w, https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-297-400x300.png 400w, https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-297-768x575.png 768w, https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-297-430x322.png 430w, https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-297-700x524.png 700w, https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-297-150x112.png 150w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1000\" height=\"749\" data-id=\"40154\" src=\"https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-298.png\" alt=\"Fabrikerkundung eines brasilianischen Kunden\" class=\"wp-image-40154\" srcset=\"https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-298.png 1000w, https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-298-400x300.png 400w, https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-298-768x575.png 768w, https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-298-430x322.png 430w, https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-298-700x524.png 700w, https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/image-298-150x112.png 150w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>Wir waren begeistert, unseren gesch\u00e4tzten brasilianischen Kunden, der unser Werk mit seiner Anwesenheit beehrte, herzlich willkommen hei\u00dfen zu k\u00f6nnen.,<\/p>","protected":false},"author":1,"featured_media":40152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[761],"tags":[773],"class_list":["post-30119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-customer-visit","tag-brazilian-customer-visit"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.harsle.com\/wp-content\/uploads\/2024\/10\/Brazilian-Customer_s-Factory-Exploration.jpg","_links":{"self":[{"href":"https:\/\/www.harsle.com\/de\/wp-json\/wp\/v2\/posts\/30119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.harsle.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.harsle.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.harsle.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.harsle.com\/de\/wp-json\/wp\/v2\/comments?post=30119"}],"version-history":[{"count":0,"href":"https:\/\/www.harsle.com\/de\/wp-json\/wp\/v2\/posts\/30119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.harsle.com\/de\/wp-json\/wp\/v2\/media\/40152"}],"wp:attachment":[{"href":"https:\/\/www.harsle.com\/de\/wp-json\/wp\/v2\/media?parent=30119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.harsle.com\/de\/wp-json\/wp\/v2\/categories?post=30119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.harsle.com\/de\/wp-json\/wp\/v2\/tags?post=30119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}